{"id":2621,"date":"2018-02-26T13:47:59","date_gmt":"2018-02-26T12:47:59","guid":{"rendered":"https:\/\/www.diocesitn.it\/famiglia\/?post_type=wd-appuntamenti&amp;p=2621"},"modified":"2018-02-26T13:47:59","modified_gmt":"2018-02-26T12:47:59","slug":"messa-e-caffe-del-giovedi-mattina-10","status":"publish","type":"wd-appuntamenti","link":"https:\/\/www.diocesitn.it\/area-annuncio\/wd-appuntamenti\/messa-e-caffe-del-giovedi-mattina-10\/","title":{"rendered":"Messa e caff\u00e8 del gioved\u00ec mattina"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"featured_media":0,"template":"","tags":[],"wd-tipo-appuntamenti":[331],"class_list":["post-2621","wd-appuntamenti","type-wd-appuntamenti","status-publish","hentry","wd-tipo-appuntamenti-preghiera"],"acf":{"noah_appuntamento_descrizione":"Ore 9.00 Celebrazione Eucaristica.\n\nA seguire, pausa caff\u00e8 e adorazione libera.\n\nore 11.00 conclusione con la recita dell\u2019ora media.\n\nDurante la Messa si rivolgono intenzioni per le famiglie. Il primo gioved\u00ec del mese, in accordo col Monastero Invisibile, si prega per le vocazioni sacerdotali, religiose e coniugali\n<p style=\"text-align: right;\"><a href=\"http:\/\/www.casaspiritualita.it\/component\/k2\/item\/38-messa-caffe.html\" target=\"_blank\" rel=\"noopener\">Per saperne di pi\u00f9<\/a><\/p>","noah_appuntamento_allday":false,"noah_appuntamento_data_inizio":"20180301","noah_info_aggiuntive_data":"","noah_appuntamento_ora_inizio":"09","noah_appuntamento_minuti_inizio":"00","noah_appuntamento_data_fine":"20180301","noah_appuntamento_ora_fine":"11","noah_appuntamento_minuti_fine":"00","noah_appuntamento_categoria":[331],"noah_appuntamento_tipo_organizzatore":"interno","noah_appuntamento_organizzatore_interno":"","noah_appuntamento_organizzatore_altro":"","noah_appuntamento_allegati":null,"seed-localization-paese-cod":"IT","seed-localization-address":"","seed-localization-citta":"Trento","seed-localization-regione-cod-istat":"04","seed-localization-citta-cod-istat":"022205","seed-localization-localita":"Trento","seed-localization-cap":"38122","seed-localization-marker-visibility":false,"seed-localization-children-visibility":false,"seed-localization-kml":null,"seed-localization-custom-marker":null,"noah_appuntamento_segnala":""},"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v20.2.1 (Yoast SEO v22.2) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Messa e caff\u00e8 del gioved\u00ec mattina - Annuncio e Sacramenti<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.diocesitn.it\/area-annuncio\/wd-appuntamenti\/messa-e-caffe-del-giovedi-mattina-10\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Messa e caff\u00e8 del gioved\u00ec mattina\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.diocesitn.it\/area-annuncio\/wd-appuntamenti\/messa-e-caffe-del-giovedi-mattina-10\/\" \/>\n<meta property=\"og:site_name\" content=\"Annuncio e Sacramenti\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/pastoralegiovanile.trento\/\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.diocesitn.it\/area-annuncio\/wp-content\/uploads\/sites\/39\/2021\/09\/og-logo-annuncio-e-sacramenti.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"630\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.diocesitn.it\/area-annuncio\/wd-appuntamenti\/messa-e-caffe-del-giovedi-mattina-10\/\",\"url\":\"https:\/\/www.diocesitn.it\/area-annuncio\/wd-appuntamenti\/messa-e-caffe-del-giovedi-mattina-10\/\",\"name\":\"Messa e caff\u00e8 del gioved\u00ec mattina - Annuncio e Sacramenti\",\"isPartOf\":{\"@id\":\"https:\/\/www.diocesitn.it\/area-annuncio\/#website\"},\"datePublished\":\"2018-02-26T12:47:59+00:00\",\"dateModified\":\"2018-02-26T12:47:59+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.diocesitn.it\/area-annuncio\/wd-appuntamenti\/messa-e-caffe-del-giovedi-mattina-10\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.diocesitn.it\/area-annuncio\/wd-appuntamenti\/messa-e-caffe-del-giovedi-mattina-10\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.diocesitn.it\/area-annuncio\/wd-appuntamenti\/messa-e-caffe-del-giovedi-mattina-10\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.diocesitn.it\/area-annuncio\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Appuntamenti\",\"item\":\"https:\/\/www.diocesitn.it\/area-annuncio\/wd-appuntamenti\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Messa e caff\u00e8 del gioved\u00ec mattina\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.diocesitn.it\/area-annuncio\/#website\",\"url\":\"https:\/\/www.diocesitn.it\/area-annuncio\/\",\"name\":\"Annuncio e Sacramenti\",\"description\":\"Chiesa di Trento\",\"publisher\":{\"@id\":\"https:\/\/www.diocesitn.it\/area-annuncio\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.diocesitn.it\/area-annuncio\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"it-IT\"},{\"@type\":[\"Organization\",\"Place\"],\"@id\":\"https:\/\/www.diocesitn.it\/area-annuncio\/#organization\",\"name\":\"Area Annuncio e Sacramenti - Chiesa di Trento\",\"url\":\"https:\/\/www.diocesitn.it\/area-annuncio\/\",\"logo\":{\"@id\":\"https:\/\/www.diocesitn.it\/area-annuncio\/wd-appuntamenti\/messa-e-caffe-del-giovedi-mattina-10\/#local-main-organization-logo\"},\"image\":{\"@id\":\"https:\/\/www.diocesitn.it\/area-annuncio\/wd-appuntamenti\/messa-e-caffe-del-giovedi-mattina-10\/#local-main-organization-logo\"},\"sameAs\":[\"https:\/\/www.facebook.com\/pastoralegiovanile.trento\/\",\"https:\/\/www.instagram.com\/pastoralegiovaniletrento\/\",\"https:\/\/www.youtube.com\/channel\/UCGt7hyJaIQIkrQPos4K6L6w\"],\"openingHoursSpecification\":[{\"@type\":\"OpeningHoursSpecification\",\"dayOfWeek\":[\"Monday\",\"Tuesday\",\"Wednesday\",\"Thursday\",\"Friday\",\"Saturday\",\"Sunday\"],\"opens\":\"09:00\",\"closes\":\"17:00\"}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.diocesitn.it\/area-annuncio\/wd-appuntamenti\/messa-e-caffe-del-giovedi-mattina-10\/#local-main-organization-logo\",\"url\":\"https:\/\/www.diocesitn.it\/area-annuncio\/wp-content\/uploads\/sites\/39\/2021\/09\/og-logo-annuncio-e-sacramenti.jpg\",\"contentUrl\":\"https:\/\/www.diocesitn.it\/area-annuncio\/wp-content\/uploads\/sites\/39\/2021\/09\/og-logo-annuncio-e-sacramenti.jpg\",\"width\":1200,\"height\":630,\"caption\":\"Area Annuncio e Sacramenti - Chiesa di Trento\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Messa e caff\u00e8 del gioved\u00ec mattina - Annuncio e Sacramenti","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.diocesitn.it\/area-annuncio\/wd-appuntamenti\/messa-e-caffe-del-giovedi-mattina-10\/","og_locale":"it_IT","og_type":"article","og_title":"Messa e caff\u00e8 del gioved\u00ec mattina","og_url":"https:\/\/www.diocesitn.it\/area-annuncio\/wd-appuntamenti\/messa-e-caffe-del-giovedi-mattina-10\/","og_site_name":"Annuncio e Sacramenti","article_publisher":"https:\/\/www.facebook.com\/pastoralegiovanile.trento\/","og_image":[{"width":1200,"height":630,"url":"https:\/\/www.diocesitn.it\/area-annuncio\/wp-content\/uploads\/sites\/39\/2021\/09\/og-logo-annuncio-e-sacramenti.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.diocesitn.it\/area-annuncio\/wd-appuntamenti\/messa-e-caffe-del-giovedi-mattina-10\/","url":"https:\/\/www.diocesitn.it\/area-annuncio\/wd-appuntamenti\/messa-e-caffe-del-giovedi-mattina-10\/","name":"Messa e caff\u00e8 del gioved\u00ec mattina - Annuncio e Sacramenti","isPartOf":{"@id":"https:\/\/www.diocesitn.it\/area-annuncio\/#website"},"datePublished":"2018-02-26T12:47:59+00:00","dateModified":"2018-02-26T12:47:59+00:00","breadcrumb":{"@id":"https:\/\/www.diocesitn.it\/area-annuncio\/wd-appuntamenti\/messa-e-caffe-del-giovedi-mattina-10\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.diocesitn.it\/area-annuncio\/wd-appuntamenti\/messa-e-caffe-del-giovedi-mattina-10\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.diocesitn.it\/area-annuncio\/wd-appuntamenti\/messa-e-caffe-del-giovedi-mattina-10\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.diocesitn.it\/area-annuncio\/"},{"@type":"ListItem","position":2,"name":"Appuntamenti","item":"https:\/\/www.diocesitn.it\/area-annuncio\/wd-appuntamenti\/"},{"@type":"ListItem","position":3,"name":"Messa e caff\u00e8 del gioved\u00ec mattina"}]},{"@type":"WebSite","@id":"https:\/\/www.diocesitn.it\/area-annuncio\/#website","url":"https:\/\/www.diocesitn.it\/area-annuncio\/","name":"Annuncio e Sacramenti","description":"Chiesa di Trento","publisher":{"@id":"https:\/\/www.diocesitn.it\/area-annuncio\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.diocesitn.it\/area-annuncio\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"it-IT"},{"@type":["Organization","Place"],"@id":"https:\/\/www.diocesitn.it\/area-annuncio\/#organization","name":"Area Annuncio e Sacramenti - Chiesa di Trento","url":"https:\/\/www.diocesitn.it\/area-annuncio\/","logo":{"@id":"https:\/\/www.diocesitn.it\/area-annuncio\/wd-appuntamenti\/messa-e-caffe-del-giovedi-mattina-10\/#local-main-organization-logo"},"image":{"@id":"https:\/\/www.diocesitn.it\/area-annuncio\/wd-appuntamenti\/messa-e-caffe-del-giovedi-mattina-10\/#local-main-organization-logo"},"sameAs":["https:\/\/www.facebook.com\/pastoralegiovanile.trento\/","https:\/\/www.instagram.com\/pastoralegiovaniletrento\/","https:\/\/www.youtube.com\/channel\/UCGt7hyJaIQIkrQPos4K6L6w"],"openingHoursSpecification":[{"@type":"OpeningHoursSpecification","dayOfWeek":["Monday","Tuesday","Wednesday","Thursday","Friday","Saturday","Sunday"],"opens":"09:00","closes":"17:00"}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.diocesitn.it\/area-annuncio\/wd-appuntamenti\/messa-e-caffe-del-giovedi-mattina-10\/#local-main-organization-logo","url":"https:\/\/www.diocesitn.it\/area-annuncio\/wp-content\/uploads\/sites\/39\/2021\/09\/og-logo-annuncio-e-sacramenti.jpg","contentUrl":"https:\/\/www.diocesitn.it\/area-annuncio\/wp-content\/uploads\/sites\/39\/2021\/09\/og-logo-annuncio-e-sacramenti.jpg","width":1200,"height":630,"caption":"Area Annuncio e Sacramenti - Chiesa di Trento"}]}},"_links":{"self":[{"href":"https:\/\/www.diocesitn.it\/area-annuncio\/wp-json\/wp\/v2\/wd-appuntamenti\/2621","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.diocesitn.it\/area-annuncio\/wp-json\/wp\/v2\/wd-appuntamenti"}],"about":[{"href":"https:\/\/www.diocesitn.it\/area-annuncio\/wp-json\/wp\/v2\/types\/wd-appuntamenti"}],"acf:term":[{"embeddable":true,"taxonomy":"wd-tipo-appuntamenti","href":"https:\/\/www.diocesitn.it\/area-annuncio\/wp-json\/wp\/v2\/wd-tipo-appuntamenti\/331"}],"wp:attachment":[{"href":"https:\/\/www.diocesitn.it\/area-annuncio\/wp-json\/wp\/v2\/media?parent=2621"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.diocesitn.it\/area-annuncio\/wp-json\/wp\/v2\/tags?post=2621"},{"taxonomy":"wd-tipo-appuntamenti","embeddable":true,"href":"https:\/\/www.diocesitn.it\/area-annuncio\/wp-json\/wp\/v2\/wd-tipo-appuntamenti?post=2621"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}